{"id":26188,"date":"2025-03-20T04:31:20","date_gmt":"2025-03-20T03:31:20","guid":{"rendered":"https:\/\/diggaeurope.com\/product\/tete-dentrainement-dancrage-xd310\/"},"modified":"2026-05-15T03:37:16","modified_gmt":"2026-05-15T02:37:16","slug":"xd310-entrainement-dancrage","status":"publish","type":"product","link":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/","title":{"rendered":"XD310 Entra\u00eenement d\u2019ancrage"},"content":{"rendered":"<h2>Entra\u00eenements d\u2019ancrage \u00e0 2 vitesses Xtreme Drive<\/h2>\n<p>Les entra\u00eenements d\u2019ancrage \u00e0 2 vitesses Xtreme Drive de Digga offrent une efficacit\u00e9 et des performances \u00e9lev\u00e9es pour l\u2019installation de pieux viss\u00e9s. Le mode vitesse \u00e9lev\u00e9e am\u00e9liore la productivit\u00e9 sur les applications l\u00e9g\u00e8res, tandis que le mode vitesse faible \u00e0 couple \u00e9lev\u00e9 offre une pr\u00e9cision accrue pour les conditions plus difficiles. Une vanne anti-retour brevet\u00e9e limite la d\u00e9compression rapide de l\u2019huile, prolongeant ainsi la dur\u00e9e de vie des composants. Le moteur \u00e0 pistons radiaux \u00e0 haut rendement garantit des performances constantes et une utilisation optimale de la puissance. Con\u00e7u pour durer, le r\u00e9ducteur robuste et le syst\u00e8me de verrouillage d\u2019arbre haute r\u00e9sistance supportent jusqu\u2019\u00e0 380 lpm sans n\u00e9cessiter de r\u00e9glage de la machine. Aucun circuit hydraulique complexe n\u2019est requis. La bo\u00eete de vitesses et le moteur sont garantis 1 an.      <\/p>\n","protected":false},"excerpt":{"rendered":"<h2>Sp\u00e9cifications<\/h2>\n<p>Cet entra\u00eenement d\u2019ancrage \u00e0 2 vitesses XD310 offre des performances \u00e9lev\u00e9es sans n\u00e9cessiter de r\u00e9glage de la machine. Sa fonction \u00e0 2 vitesses permet de basculer entre une vitesse \u00e9lev\u00e9e pour les mat\u00e9riaux l\u00e9gers et une \u00e9vacuation rapide des d\u00e9blais, et un couple \u00e9lev\u00e9 pour les conditions de sol difficiles et les outils de grand diam\u00e8tre. Disponible en versions 12 V ou 24 V, le XD310 est compatible avec une large gamme de machines et fonctionne avec des d\u00e9bits allant jusqu\u2019\u00e0 380 lpm \u00e0 240 bar. Con\u00e7u pour les applications exigeantes, il offre des performances, une fiabilit\u00e9 et une efficacit\u00e9 \u00e9lev\u00e9es.   <\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"product_brand":[],"product_cat":[248],"product_tag":[],"class_list":["post-26188","product","type-product","status-publish","product_cat-entrainement-dancrage","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XD310 Entra\u00eenement d\u2019ancrage - Digga Europe<\/title>\n<meta name=\"description\" content=\"Nous fabriquons des t\u00eates d&#039;entra\u00eenement d&#039;ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu&#039;\u00e0 304 000 Nm de couple.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XD310 Entra\u00eenement d\u2019ancrage - Digga Europe\" \/>\n<meta property=\"og:description\" content=\"Nous fabriquons des t\u00eates d&#039;entra\u00eenement d&#039;ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu&#039;\u00e0 304 000 Nm de couple.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/\" \/>\n<meta property=\"og:site_name\" content=\"Digga Europe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T02:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diggaeurope.com\/wp-content\/uploads\/2025\/03\/XD310-torque-head-digga-product.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/produit\\\/xd310-entrainement-dancrage\\\/\",\"url\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/produit\\\/xd310-entrainement-dancrage\\\/\",\"name\":\"XD310 Entra\u00eenement d\u2019ancrage - Digga Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-03-20T03:31:20+00:00\",\"dateModified\":\"2026-05-15T02:37:16+00:00\",\"description\":\"Nous fabriquons des t\u00eates d'entra\u00eenement d'ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu'\u00e0 304 000 Nm de couple.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/produit\\\/xd310-entrainement-dancrage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/produit\\\/xd310-entrainement-dancrage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/produit\\\/xd310-entrainement-dancrage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"XD310 Entra\u00eenement d\u2019ancrage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/\",\"name\":\"Digga Europe\",\"description\":\"Machinery attachments for earthmoving and construction\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diggaeurope.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XD310 Entra\u00eenement d\u2019ancrage - Digga Europe","description":"Nous fabriquons des t\u00eates d'entra\u00eenement d'ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu'\u00e0 304 000 Nm de couple.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/","og_locale":"fr_FR","og_type":"article","og_title":"XD310 Entra\u00eenement d\u2019ancrage - Digga Europe","og_description":"Nous fabriquons des t\u00eates d'entra\u00eenement d'ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu'\u00e0 304 000 Nm de couple.","og_url":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/","og_site_name":"Digga Europe","article_modified_time":"2026-05-15T02:37:16+00:00","og_image":[{"width":540,"height":540,"url":"https:\/\/diggaeurope.com\/wp-content\/uploads\/2025\/03\/XD310-torque-head-digga-product.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/","url":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/","name":"XD310 Entra\u00eenement d\u2019ancrage - Digga Europe","isPartOf":{"@id":"https:\/\/diggaeurope.com\/fr\/#website"},"datePublished":"2025-03-20T03:31:20+00:00","dateModified":"2026-05-15T02:37:16+00:00","description":"Nous fabriquons des t\u00eates d'entra\u00eenement d'ancrage pour les pelles de 50 \u00e0 80 tonnes. Ce XD310 \u00e0 2 vitesses produit jusqu'\u00e0 304 000 Nm de couple.","breadcrumb":{"@id":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diggaeurope.com\/fr\/produit\/xd310-entrainement-dancrage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diggaeurope.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/diggaeurope.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"XD310 Entra\u00eenement d\u2019ancrage"}]},{"@type":"WebSite","@id":"https:\/\/diggaeurope.com\/fr\/#website","url":"https:\/\/diggaeurope.com\/fr\/","name":"Digga Europe","description":"Machinery attachments for earthmoving and construction","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diggaeurope.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/product\/26188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/media?parent=26188"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/product_brand?post=26188"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/product_cat?post=26188"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/diggaeurope.com\/fr\/wp-json\/wp\/v2\/product_tag?post=26188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}